{"id":17191,"date":"2023-10-30T14:25:46","date_gmt":"2023-10-30T14:25:46","guid":{"rendered":"https:\/\/bordeaux-cab.com\/hourly\/"},"modified":"2024-04-29T10:52:05","modified_gmt":"2024-04-29T10:52:05","slug":"hourly-disposal-private-driver","status":"publish","type":"page","link":"https:\/\/bordeaux-cab.com\/en\/hourly-disposal-private-driver\/","title":{"rendered":"Hourly disposal of a private driver"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Page Title Section&#8221; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;RGBA(255,255,255,0)&#8221; background_image=&#8221;https:\/\/bordeaux-cab.com\/wp-content\/uploads\/2023\/12\/test-1900&#215;1080-1.jpg&#8221; background_size=&#8221;custom&#8221; background_image_width=&#8221;100%&#8221; background_image_height=&#8221;100%&#8221; custom_margin=&#8221;-130px||||false|false&#8221; custom_padding=&#8221;11px||6px|||&#8221; background_last_edited=&#8221;on|phone&#8221; background_image_phone=&#8221;https:\/\/bordeaux-cab.com\/wp-content\/uploads\/2023\/12\/mise-a-disposition-800&#215;1200-1.jpg&#8221; background_enable_image_phone=&#8221;on&#8221; background_size_phone=&#8221;contain&#8221; background_position_phone=&#8221;top_center&#8221; background_vertical_offset_phone=&#8221;5%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; use_custom_gutter=&#8221;on&#8221; make_equal=&#8221;on&#8221; admin_label=&#8221;Hero Area&#8221; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;a9206487-5970-4fb3-b5c0-1d03ba3a6175&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; width=&#8221;100%&#8221; max_width=&#8221;1337px&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;160px||80px||false|false&#8221; custom_padding_tablet=&#8221;160px||80px||false|false&#8221; custom_padding_phone=&#8221;160px||80px||false|false&#8221; custom_padding_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_cta title=&#8221;Hourly disposal of a vehicle with private driver in Bordeaux&#8221; button_url=&#8221;#&#8221; admin_label=&#8221;Hero Text&#8221; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; header_level=&#8221;h1&#8243; header_font=&#8221;Poppins|600|||||||&#8221; header_text_align=&#8221;center&#8221; header_font_size=&#8221;40px&#8221; header_line_height=&#8221;1.4em&#8221; body_font=&#8221;Poppins||||||||&#8221; body_font_size=&#8221;18px&#8221; body_line_height=&#8221;1.8em&#8221; use_background_color=&#8221;off&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#2a2a2a&#8221; button_bg_color=&#8221;#ffffff&#8221; button_border_width=&#8221;12px&#8221; button_border_color=&#8221;#ffffff&#8221; button_letter_spacing=&#8221;2px&#8221; button_font=&#8221;Poppins|600||on|||||&#8221; button_icon=&#8221;&#x24;||divi||400&#8243; text_orientation=&#8221;left&#8221; custom_margin=&#8221;50px||||false|false&#8221; custom_padding=&#8221;|5px||5px|false|true&#8221; animation_style=&#8221;fade&#8221; header_font_size_tablet=&#8221;40px&#8221; header_font_size_phone=&#8221;30px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_cta][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_code raw_content_tablet=&#8221;%91easytaxioffice type=%22booking-widget%22%93&#8243; raw_content_phone=&#8221;%91easytaxioffice type=%22booking-widget%22%93&#8243; raw_content_last_edited=&#8221;on|phone&#8221; admin_label=&#8221;Coded&#8221; module_class=&#8221;testclass&#8221; _builder_version=&#8221;4.25.0&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;|10px|20px|10px|false|false&#8221; hover_enabled=&#8221;0&#8243; custom_css_free_form=&#8221;@media only screen and (min-width: 768px) and (max-width: 1024px) {||  .your-element-class {||    \/* Your CSS properties here *\/||  }||}&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<iframe loading=\"lazy\" src=\"https:\/\/app.bordeaux-cab.com\/booking\/widget?site_key=8bfbe8fd95ce54bf7e9d9f012fe9c37d&lang=\"auto\"\" name=\"eto-iframe\" id=\"eto-iframe-69942\" class=\"eto-iframe\" style=\"width:1px; min-width:100%; border:0;\" width=\"100%\" height=\"250\" scrolling=\"no\" allow=\"geolocation\">This option will not work correctly. Unfortunately, your browser does not support inline frames.<\/iframe>\n<script type=\"text\/javascript\" async defer> (function() { var etoWidgetData = { checkTimeout: 100, googlePageSpeed: 0, googlePageSpeedLoadDelay: 6000, loadDelay: 0, }; function etoWidgetDocReady(fn) { if (document.readyState === 'complete' || document.readyState === 'interactive') { setTimeout(fn, 1); } else { document.addEventListener('DOMContentLoaded', fn); } } function etoWidgetReplaceUrlParam(url, paramName, paramValue) { var regex = new RegExp('([?;&])'+ paramName +'[^&;]*[;&]?'); var query = url.replace(regex, '$1').replace(\/&$\/, ''); return (query.length > 2 ? query + '&' : '?') + (paramValue ? paramName +'='+ paramValue : ''); } function etoWidgetInit() { iFrameResize({ log: false, targetOrigin: '*', checkOrigin: false, }, \"iframe#eto-iframe-69942\"); etoWidgetDocReady(function() { var elSelect = document.getElementById('gtranslate_selector'); if (elSelect) { elSelect.addEventListener('change', function(event) { var selectedLang = event.target.value ? event.target.value.split('|')[1] : null; var elIframe = document.getElementById('eto-iframe-69942'); if (elIframe && selectedLang !== null) { elIframe.src = etoWidgetReplaceUrlParam(elIframe.src, 'lang', selectedLang); } event.preventDefault(); }); } }); } function etoWidgetReady() { setTimeout(function() { etoWidgetData.checkTimeout--; if (typeof iFrameResize !== 'undefined') { etoWidgetInit(); } else if (etoWidgetData.checkTimeout > 0) { etoWidgetReady(); console.log('Library not loaded, checking again.'); } else { console.log('External library failed to load.'); } }, 100); }; if (etoWidgetData.loadDelay) { setTimeout(function() { etoWidgetReady(); }, etoWidgetData.loadDelay); } else { etoWidgetReady(); } })(); <\/script>\n<!-- [et_pb_line_break_holder] -->[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Service&#8221; _builder_version=&#8221;4.22.1&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||0px|||&#8221; collapsed=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;4px|||||&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.22.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;e90600ca-045a-46d7-9ea7-c9c87c7c8a82&#8243; header_2_font=&#8221;Poppins|500|||||||&#8221; header_2_text_color=&#8221;#000000&#8243; header_2_font_size=&#8221;40px&#8221; custom_margin=&#8221;||10px||false|false&#8221; header_2_font_size_tablet=&#8221;40px&#8221; header_2_font_size_phone=&#8221;25px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Hourly \/ Daily \/ Weekly availability  <\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;56c1cf04-70fd-4163-8fac-8c737952457e&#8221; text_font=&#8221;Poppins||||||||&#8221; text_text_color=&#8221;#000000&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: justify;\"><span>Bordeaux is a very touristy city. Its location between the sea and the mountains offers you the opportunity to enjoy a wonderful stay. You can enjoy the beach, skiing, or the relaxing peace and quiet of the hinterland.<\/span><\/p>\n<p style=\"text-align: justify;\"><span>Opt for a chauffeur-driven car rental service for your travels. Whatever your reason, <strong>Bordeaux-Cab <\/strong>will meet your transfer needs. <\/span><\/p>\n<p style=\"text-align: justify;\"><span>So, for a few hours, a day, a week, or any length of time you choose, you&#8217;ll have an <strong>experienced driver to help you discover the region<\/strong>. Your driver knows the area inside out, and will be the perfect partner to take you to all the places you want to visit. He can also advise you on places to see and things to do during your stay. Thanks to our service, you won&#8217;t have to take public transport or worry about parking your rental car. <\/span>It&#8217;s <strong>the alternative of choice to taxis in Bordeaux<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><span>You can benefit from our service for as long as you wish. Hourly, daily, weekly &#8211; you decide. Our driver will remain<strong> at your disposal<\/strong> and do his utmost to satisfy your requests.<\/span><\/p>\n<p style=\"text-align: justify;\">\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Hero Section&#8221; _builder_version=&#8221;4.23.1&#8243; background_color=&#8221;#f9cb40&#8243; background_enable_image=&#8221;off&#8221; custom_padding=&#8221;80px||40px||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row admin_label=&#8221;Hero Area&#8221; _builder_version=&#8221;4.16&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_cta title=&#8221;Are you planning one or more trips?&#8221; admin_label=&#8221;Hero Text&#8221; _builder_version=&#8221;4.22.2&#8243; header_font=&#8221;Poppins|600|||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#000000&#8243; header_font_size=&#8221;32px&#8221; header_line_height=&#8221;1.4em&#8221; body_font=&#8221;Poppins||||||||&#8221; body_text_color=&#8221;#000000&#8243; body_font_size=&#8221;18px&#8221; body_line_height=&#8221;1.8em&#8221; use_background_color=&#8221;off&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#2a2a2a&#8221; button_bg_color=&#8221;#ffffff&#8221; button_border_width=&#8221;12px&#8221; button_border_color=&#8221;#ffffff&#8221; button_letter_spacing=&#8221;2px&#8221; button_font=&#8221;Poppins|600||on|||||&#8221; button_icon=&#8221;&#x24;||divi||400&#8243; max_width=&#8221;700px&#8221; module_alignment=&#8221;center&#8221; animation_style=&#8221;fade&#8221; header_font_size_tablet=&#8221;32px&#8221; header_font_size_phone=&#8221;32px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;]<\/p>\n<p>Whether for<strong> weddings<\/strong>, <strong>tourism<\/strong> or <strong>business trips<\/strong>, opt for a private chauffeur-driven rental service for your events.<\/p>\n<p>[\/et_pb_cta][et_pb_button button_url=&#8221;https:\/\/bordeaux-cab.com\/en\/contact\/&#8221; button_text=&#8221;Contact&#8221; button_alignment=&#8221;center&#8221; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_color=&#8221;#000000&#8243; button_bg_color=&#8221;#FFFFFF&#8221; button_border_color=&#8221;#FFFFFF&#8221; button_border_radius=&#8221;8px&#8221; button_font=&#8221;Poppins|||on|||||&#8221; custom_margin=&#8221;-41px|||||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;3b28eee5-ed23-4d6c-aaf8-09e62ed7fd32&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;Poppins||||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#000000&#8243; header_2_text_align_tablet=&#8221;center&#8221; header_2_text_align_phone=&#8221;center&#8221; header_2_text_align_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2 style=\"text-align: center;\">Popular destinations around Bordeaux<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; use_custom_gutter=&#8221;on&#8221; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;3b28eee5-ed23-4d6c-aaf8-09e62ed7fd32&#8243; max_width=&#8221;1389px&#8221; custom_margin=&#8221;-23px|auto||auto|false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|600|||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;16px&#8221; global_colors_info=&#8221;{}&#8221;]<a href=\"https:\/\/bordeaux-cab.com\/en\/transfer-bordeaux-saint-emilion\/\"style=\"color: black;\">Transfer from Bordeaux to Saint-\u00c9milion<\/a><\/p>\n<p><a href=\"https:\/\/bordeaux-cab.com\/en\/transfer-bordeaux-libourne\/\"style=\"color: black;\">Transfer from Bordeaux to Libourne<\/a><\/p>\n<p><a href=\"https:\/\/bordeaux-cab.com\/en\/transfer-bordeaux-lacanau\/\"style=\"color: black;\">Transfer from Bordeaux to Lacanau<\/a><\/p>\n<p><a href=\"https:\/\/bordeaux-cab.com\/en\/transfer-bordeaux-blaye\/\"style=\"color: black;\">Transfer from Bordeaux to Blaye<\/a><\/p>\n<p><a href=\"https:\/\/bordeaux-cab.com\/en\/transfer-bordeaux-dax\/\"style=\"color: black;\">Transfer from Bordeaux to Dax<\/a>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|600|||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;16px&#8221; global_colors_info=&#8221;{}&#8221;]<a href=\"https:\/\/bordeaux-cab.com\/en\/transfer-bordeaux-langon\/\" style=\"color: black;\">Transfer from Bordeaux to Langon<\/a><\/p>\n<p><a href=\"https:\/\/bordeaux-cab.com\/en\/transfer-bordeaux-sauveterre-de-guyenne\/\"style=\"color: black;\"><span>Transfer from Bordeaux to Sauveterre-de-Guyenne<\/span><\/a><\/p>\n<p><a href=\"https:\/\/bordeaux-cab.com\/en\/transfer-bordeaux-bergerac\/\"style=\"color: black;\"><span>Transfer from Bordeaux to Bergerac<\/span><\/a><\/p>\n<p><a href=\"https:\/\/bordeaux-cab.com\/en\/transfer-bordeaux-biscarrosse\/\"style=\"color: black;\"><span>Transfer from Bordeaux to Biscarosse<\/span><\/a><\/p>\n<p><a href=\"https:\/\/bordeaux-cab.com\/transfert-bordeaux-pauillac\/\"style=\"color: black;\"><span>Transfer from Bordeaux to Pauillac<\/span><\/a>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Poppins|600|||||||&#8221; text_text_color=&#8221;#000000&#8243; text_font_size=&#8221;16px&#8221; global_colors_info=&#8221;{}&#8221;]<a href=\"https:\/\/bordeaux-cab.com\/en\/transfer-bordeaux-la-roche-chalais\/\"style=\"color: black;\"><span>Transfer from Bordeaux to La Roche-Chalais<\/span><\/a><\/p>\n<p><a href=\"https:\/\/bordeaux-cab.com\/en\/transfer-bordeaux-royan\/\"style=\"color: black;\"><span>Transfer from Bordeaux to Royan<\/span><\/a><\/p>\n<p><a href=\"https:\/\/bordeaux-cab.com\/en\/transfer-bordeaux-saintes\/\"style=\"color: black;\"><span>Transfer from Bordeaux to Saintes<\/span><\/a><\/p>\n<p><a href=\"https:\/\/bordeaux-cab.com\/en\/transfer-bordeaux-la-rochelle\/\"style=\"color: black;\"><span>Transfer from Bordeaux to La Rochelle<\/span><\/a><\/p>\n<p><a href=\"https:\/\/bordeaux-cab.com\/en\/transfer-bordeaux-arcachon\/\"style=\"color: black;\"><span>Transfer from Bordeaux to Arcachon<\/span><\/a><\/p>\n<p><span><\/span>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p><iframe loading=\"lazy\" src=\"https:\/\/app.bordeaux-cab.com\/booking\/widget?site_key=8bfbe8fd95ce54bf7e9d9f012fe9c37d&lang=\"auto\"\" name=\"eto-iframe\" id=\"eto-iframe-35388\" class=\"eto-iframe\" style=\"width:1px; min-width:100%; border:0;\" width=\"100%\" height=\"250\" scrolling=\"no\" allow=\"geolocation\">This option will not work correctly. Unfortunately, your browser does not support inline frames.<\/iframe>\n<script type=\"text\/javascript\" async defer> (function() { var etoWidgetData = { checkTimeout: 100, googlePageSpeed: 0, googlePageSpeedLoadDelay: 6000, loadDelay: 0, }; function etoWidgetDocReady(fn) { if (document.readyState === 'complete' || document.readyState === 'interactive') { setTimeout(fn, 1); } else { document.addEventListener('DOMContentLoaded', fn); } } function etoWidgetReplaceUrlParam(url, paramName, paramValue) { var regex = new RegExp('([?;&])'+ paramName +'[^&;]*[;&]?'); var query = url.replace(regex, '$1').replace(\/&$\/, ''); return (query.length > 2 ? query + '&' : '?') + (paramValue ? paramName +'='+ paramValue : ''); } function etoWidgetInit() { iFrameResize({ log: false, targetOrigin: '*', checkOrigin: false, }, \"iframe#eto-iframe-35388\"); etoWidgetDocReady(function() { var elSelect = document.getElementById('gtranslate_selector'); if (elSelect) { elSelect.addEventListener('change', function(event) { var selectedLang = event.target.value ? event.target.value.split('|')[1] : null; var elIframe = document.getElementById('eto-iframe-35388'); if (elIframe && selectedLang !== null) { elIframe.src = etoWidgetReplaceUrlParam(elIframe.src, 'lang', selectedLang); } event.preventDefault(); }); } }); } function etoWidgetReady() { setTimeout(function() { etoWidgetData.checkTimeout--; if (typeof iFrameResize !== 'undefined') { etoWidgetInit(); } else if (etoWidgetData.checkTimeout > 0) { etoWidgetReady(); console.log('Library not loaded, checking again.'); } else { console.log('External library failed to load.'); } }, 100); }; if (etoWidgetData.loadDelay) { setTimeout(function() { etoWidgetReady(); }, etoWidgetData.loadDelay); } else { etoWidgetReady(); } })(); <\/script>\nHourly \/ Daily \/ Weekly availability Bordeaux is a very touristy city. Its location between the sea and the mountains offers you the opportunity to enjoy a wonderful stay. You can enjoy the beach, skiing, or the relaxing peace and quiet of the hinterland. Opt for a chauffeur-driven car rental service for your travels. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-17191","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/bordeaux-cab.com\/en\/wp-json\/wp\/v2\/pages\/17191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bordeaux-cab.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bordeaux-cab.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bordeaux-cab.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bordeaux-cab.com\/en\/wp-json\/wp\/v2\/comments?post=17191"}],"version-history":[{"count":15,"href":"https:\/\/bordeaux-cab.com\/en\/wp-json\/wp\/v2\/pages\/17191\/revisions"}],"predecessor-version":[{"id":19485,"href":"https:\/\/bordeaux-cab.com\/en\/wp-json\/wp\/v2\/pages\/17191\/revisions\/19485"}],"wp:attachment":[{"href":"https:\/\/bordeaux-cab.com\/en\/wp-json\/wp\/v2\/media?parent=17191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}